{"id":1524,"date":"2024-12-11T09:20:37","date_gmt":"2024-12-11T08:20:37","guid":{"rendered":"https:\/\/etxebetea.com\/contacto\/"},"modified":"2024-12-27T13:47:57","modified_gmt":"2024-12-27T12:47:57","slug":"contacto","status":"publish","type":"page","link":"https:\/\/etxebetea.com\/en\/contacto\/","title":{"rendered":"Contact"},"content":{"rendered":"\n<div id=\"cabecera\" class=\"wp-block-group page-header page-header--small\"><div class=\"wp-block-group__inner-container is-layout-constrained wp-block-group-is-layout-constrained\">\n<h1 class=\"wp-block-heading\">Contact<\/h1>\n\n\n\n<p class=\"has-larger-font-size\">Write us with any questions or send us an email<\/p>\n<\/div><\/div>\n\n\n<div class=\"wpforms-container wpforms-container-full\" id=\"wpforms-1530\"><form id=\"wpforms-form-1530\" class=\"wpforms-validate wpforms-form wpforms-ajax-form\" data-formid=\"1530\" method=\"post\" enctype=\"multipart\/form-data\" action=\"\/en\/wp-json\/wp\/v2\/pages\/1524\" data-token=\"c9cced0fe32c4fa6483531a8dfecca78\"><noscript class=\"wpforms-error-noscript\">Please enable JavaScript in your browser to complete this form.<\/noscript><div class=\"wpforms-field-container\"><div id=\"wpforms-1530-field_0-container\" class=\"wpforms-field wpforms-field-name\" data-field-id=\"0\"><label class=\"wpforms-field-label wpforms-label-hide\" for=\"wpforms-1530-field_0\">Nombre <span class=\"wpforms-required-label\">*<\/span><\/label><input type=\"text\" id=\"wpforms-1530-field_0\" class=\"wpforms-field-large wpforms-field-required\" name=\"wpforms[fields][0]\" placeholder=\"What is your name?\" required><\/div><div id=\"wpforms-1530-field_1-container\" class=\"wpforms-field wpforms-field-email\" data-field-id=\"1\"><label class=\"wpforms-field-label wpforms-label-hide\" for=\"wpforms-1530-field_1\">Email <span class=\"wpforms-required-label\">*<\/span><\/label><input type=\"email\" id=\"wpforms-1530-field_1\" class=\"wpforms-field-large wpforms-field-required\" name=\"wpforms[fields][1]\" placeholder=\"What is your e-mail?\" required><\/div><div id=\"wpforms-1530-field_3-container\" class=\"wpforms-field wpforms-field-text\" data-field-id=\"3\"><label class=\"wpforms-field-label wpforms-label-hide\" for=\"wpforms-1530-field_3\">Asunto<\/label><input type=\"text\" id=\"wpforms-1530-field_3\" class=\"wpforms-field-large\" name=\"wpforms[fields][3]\" placeholder=\"What do you want to talk about?\" ><\/div><div id=\"wpforms-1530-field_2-container\" class=\"wpforms-field wpforms-field-textarea\" data-field-id=\"2\"><label class=\"wpforms-field-label wpforms-label-hide\" for=\"wpforms-1530-field_2\">Mensaje<\/label><textarea id=\"wpforms-1530-field_2\" class=\"wpforms-field-medium\" name=\"wpforms[fields][2]\" placeholder=\"Tell us more!\" ><\/textarea><\/div><\/div><input type=\"hidden\" name=\"wpforms[recaptcha]\" value=\"\"><div class=\"wpforms-submit-container\"><input type=\"hidden\" name=\"wpforms[id]\" value=\"1530\"><input type=\"hidden\" name=\"wpforms[author]\" value=\"1\"><button type=\"submit\" name=\"wpforms[submit]\" id=\"wpforms-submit-1530\" class=\"wpforms-submit\" data-alt-text=\"Sending...\" data-submit-text=\"Send\" aria-live=\"assertive\" value=\"wpforms-submit\">Send<\/button><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/etxebetea.com\/wp-content\/plugins\/wpforms\/assets\/images\/submit-spin.svg\" class=\"wpforms-submit-spinner\" style=\"display: none;\" width=\"26\" height=\"26\" alt=\"Loading\"><\/div><\/form><\/div>  <!-- .wpforms-container -->","protected":false},"excerpt":{"rendered":"<p>Contact Write us with any questions or send us an email<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"inline_featured_image":false,"_genesis_hide_title":true,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","footnotes":""},"class_list":{"0":"post-1524","1":"page","2":"type-page","3":"status-publish","5":"entry"},"acf":[],"_links":{"self":[{"href":"https:\/\/etxebetea.com\/en\/wp-json\/wp\/v2\/pages\/1524","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/etxebetea.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/etxebetea.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/etxebetea.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/etxebetea.com\/en\/wp-json\/wp\/v2\/comments?post=1524"}],"version-history":[{"count":2,"href":"https:\/\/etxebetea.com\/en\/wp-json\/wp\/v2\/pages\/1524\/revisions"}],"predecessor-version":[{"id":1533,"href":"https:\/\/etxebetea.com\/en\/wp-json\/wp\/v2\/pages\/1524\/revisions\/1533"}],"wp:attachment":[{"href":"https:\/\/etxebetea.com\/en\/wp-json\/wp\/v2\/media?parent=1524"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}